{"id":1024,"date":"2016-07-06T11:45:20","date_gmt":"2016-07-06T09:45:20","guid":{"rendered":"https:\/\/www.wikeo.be\/blog\/?p=1024"},"modified":"2020-07-12T09:20:59","modified_gmt":"2020-07-12T07:20:59","slug":"menu-edition-adaptatif-tri-annuaire","status":"publish","type":"post","link":"https:\/\/www.wikeo.be\/blog\/2016\/07\/06\/menu-edition-adaptatif-tri-annuaire\/","title":{"rendered":"Menu d&rsquo;\u00e9dition adaptatif et tri dans l&rsquo;annuaire"},"content":{"rendered":"<p>Comme indiqu\u00e9 dans notre pr\u00e9c\u00e9dent article sur la v4 de Wikeo, nous proc\u00e9dons \u00e0 des petites mises \u00e0 jour ponctuelles.<\/p>\n<h2>Tri dans l&rsquo;annuaire de sites<\/h2>\n<p>L&rsquo;annuaire de Wikeo permet \u00e0 chaque nouveau site de se retrouver plus facilement sur Google. En effet, pour que Google connaisse un nouveau site web, il faut que des <a href=\"https:\/\/www.wikeo.be\/blog\/2011\/07\/01\/comment-apparaitre-referencement-google\/\">liens arrivent dessus<\/a>. Le soucis est que nous avons eu beaucoup d&rsquo;abus : des sites sans contenu ou avec un contenu trop pauvre se retrouvent devant des sites ayant un r\u00e9el int\u00e9r\u00eat&#8230; Ce qui n&rsquo;est pas juste !<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1034\" src=\"https:\/\/www.wikeo.be\/blog\/wp-content\/uploads\/2016\/07\/787ae9ec9023a82f5aa7e4c1a64f73cb_XL.jpg\" alt=\"Tri dans l'annuaire\" width=\"1240\" height=\"600\" srcset=\"https:\/\/www.wikeo.be\/blog\/wp-content\/uploads\/2016\/07\/787ae9ec9023a82f5aa7e4c1a64f73cb_XL.jpg 1240w, https:\/\/www.wikeo.be\/blog\/wp-content\/uploads\/2016\/07\/787ae9ec9023a82f5aa7e4c1a64f73cb_XL-300x145.jpg 300w, https:\/\/www.wikeo.be\/blog\/wp-content\/uploads\/2016\/07\/787ae9ec9023a82f5aa7e4c1a64f73cb_XL-768x372.jpg 768w, https:\/\/www.wikeo.be\/blog\/wp-content\/uploads\/2016\/07\/787ae9ec9023a82f5aa7e4c1a64f73cb_XL-1024x495.jpg 1024w, https:\/\/www.wikeo.be\/blog\/wp-content\/uploads\/2016\/07\/787ae9ec9023a82f5aa7e4c1a64f73cb_XL-624x302.jpg 624w\" sizes=\"auto, (max-width: 1240px) 100vw, 1240px\" \/><\/p>\n<p>Nous avons donc trouv\u00e9 la parade : les sites de mauvaise qualit\u00e9 sont maintenant d\u00e9tect\u00e9s par nos robots et marqu\u00e9s en tant que tel tant que du contenu correct n&rsquo;a pas \u00e9t\u00e9 ins\u00e9r\u00e9 dessus. Votre site r\u00e9dig\u00e9 avec s\u00e9rieux se retrouvera donc mieux class\u00e9 ! Pour vous retrouver simplement dans cet annuaire, il suffit de cr\u00e9er un site, et personnaliser le contenu des nouvelles pages.<\/p>\n<h2>Menu d&rsquo;\u00e9dition adaptatif<\/h2>\n<p>Les PC portables de petites dimensions (de 11 \u00e0 13 pouces) sont monnaie courante, entre les Macbook Air et les tout-en-un Microsoft, le parc informatique \u00e9volue. Nous nous adaptons donc et les technologies web actuelles nous permettent d&rsquo;adapter facilement du contenu en fonction de la r\u00e9solution d&rsquo;\u00e9cran.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1035\" src=\"https:\/\/www.wikeo.be\/blog\/wp-content\/uploads\/2016\/07\/juil.-06-2016-11-39-38.gif\" alt=\"Exemple montrant comment le menu d'\u00e9dition s'adapte aux r\u00e9solutions d'\u00e9cran\" width=\"480\" height=\"711\"><\/p>\n<p>Le menu d&rsquo;\u00e9dition de contenu dispose maintenant de 3 \u00e9tats : un menu complet, un menu abr\u00e9g\u00e9 et un menu \u00ab\u00a0mini\u00a0\u00bb. Quelle que soit la r\u00e9solution de votre \u00e9cran, le menu s&rsquo;affiche en une seule colonne et dans son enti\u00e8ret\u00e9 !<\/p>\n<h2>Nouveaux captchas<\/h2>\n<p>Lors de la cr\u00e9ation d&rsquo;un site ou lorsque vos visiteurs vous contactent, un syst\u00e8me de captcha (une illustration repr\u00e9sentant des chiffres ou des lettres \u00e0 recopier) permet de filtrer les robots spammeurs. Le probl\u00e8me est que ce captcha est souvent soit illisible soit trop facilement lisible pour emb\u00eater les robots. Devant ce constat et l&rsquo;inefficacit\u00e9 de notre captcha, nous avons pris la d\u00e9cision de changer de syst\u00e8me.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1029 size-medium\" src=\"https:\/\/www.wikeo.be\/blog\/wp-content\/uploads\/2016\/07\/Capture-d\u2019e\u0301cran-2016-07-05-a\u0300-09.08.29-300x75.png\" alt=\"Nous ne sommes pas des robots !\" width=\"300\" height=\"75\" srcset=\"https:\/\/www.wikeo.be\/blog\/wp-content\/uploads\/2016\/07\/Capture-d\u2019e\u0301cran-2016-07-05-a\u0300-09.08.29-300x75.png 300w, https:\/\/www.wikeo.be\/blog\/wp-content\/uploads\/2016\/07\/Capture-d\u2019e\u0301cran-2016-07-05-a\u0300-09.08.29-768x193.png 768w, https:\/\/www.wikeo.be\/blog\/wp-content\/uploads\/2016\/07\/Capture-d\u2019e\u0301cran-2016-07-05-a\u0300-09.08.29-624x157.png 624w, https:\/\/www.wikeo.be\/blog\/wp-content\/uploads\/2016\/07\/Capture-d\u2019e\u0301cran-2016-07-05-a\u0300-09.08.29.png 812w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Nous avons choisi <a href=\"https:\/\/www.google.com\/recaptcha\/intro\/index.html\">reCaptcha<\/a>, un service de Google assez original : de base ils rep\u00e8rent une s\u00e9rie de param\u00e8tres du visiteur. Si ces param\u00e8tres ne correspondent pas \u00e0 un robot, une simple case \u00e0 cocher est pr\u00e9sent\u00e9e, ainsi, il n&rsquo;y a pas de code illisible \u00e0 recopier. Si en revanche un doute est permis, un challenge est demand\u00e9 \u00e0 l&rsquo;utilisateur.<\/p>\n<p>L\u00e0 o\u00f9 reCaptcha est fantastique&nbsp;c&rsquo;est que le challenge sert r\u00e9ellement \u00e0 quelque chose : soit \u00e0 am\u00e9liorer les algorithmes de reconnaissance d&rsquo;images, soit \u00e0 am\u00e9liorer la lecture automatis\u00e9e d&rsquo;ouvrages anciens. Alors que r\u00e9soudre des&nbsp;captchas ordinaires ne sert&nbsp;\u00e0 rien d&rsquo;autre qu&rsquo;\u00e0 prouver que nous ne sommes pas des robots&#8230;<\/p>\n<h2>Am\u00e9liorations diverses<\/h2>\n<p>En dehors de ces changements d&rsquo;importance, nous avons continu\u00e9 \u00e0 am\u00e9liorer nos services&nbsp;\u00e0 diff\u00e9rents niveaux visibles ou moins visibles :<\/p>\n<ul>\n<li>Am\u00e9lioration du temps de chargement de la page d&rsquo;accueil de Wikeo<\/li>\n<li>Remplacement des paliers de t\u00e9l\u00e9phone Belges par 3 et 4\u20ac (au lieux de 1,2 et 2,5\u20ac) pour les abonnements.<\/li>\n<li>Am\u00e9lioration des performances de l&rsquo;\u00e9diteur de pages<\/li>\n<li>Am\u00e9lioration de la stabilit\u00e9 de l&rsquo;\u00e9diteur de pages<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Comme indiqu\u00e9 dans notre pr\u00e9c\u00e9dent article sur la v4 de Wikeo, nous proc\u00e9dons \u00e0 des petites mises \u00e0 jour ponctuelles. Tri dans l&rsquo;annuaire de sites L&rsquo;annuaire de Wikeo permet \u00e0 chaque nouveau site de se retrouver plus facilement sur Google. En effet, pour que Google connaisse un nouveau site web, il faut que des liens [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1172,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[6],"tags":[83,8],"class_list":["post-1024","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite-de-wikeo","tag-creer-un-site","tag-wikeo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tri dans l&#039;annuaire, nouveaux captcha et menus sur Wikeo<\/title>\n<meta name=\"description\" content=\"Wikeo v4 avance et cr\u00e9er un site sur Wikeo est encore plus simple avec la v4. Venez d\u00e9couvrir les nouveaut\u00e9s du mois de juillet 2016 !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.wikeo.be\/blog\/2016\/07\/06\/menu-edition-adaptatif-tri-annuaire\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tri dans l&#039;annuaire, nouveaux captcha et menus sur Wikeo\" \/>\n<meta property=\"og:description\" content=\"Wikeo v4 avance et cr\u00e9er un site sur Wikeo est encore plus simple avec la v4. Venez d\u00e9couvrir les nouveaut\u00e9s du mois de juillet 2016 !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.wikeo.be\/blog\/2016\/07\/06\/menu-edition-adaptatif-tri-annuaire\/\" \/>\n<meta property=\"og:site_name\" content=\"Cr\u00e9er un site internet avec Wikeo : Astuces et conseils\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wikeocom\" \/>\n<meta property=\"article:published_time\" content=\"2016-07-06T09:45:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-12T07:20:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.wikeo.be\/blog\/wp-content\/uploads\/2016\/07\/gary-chan-YzSZN3qvHeo-unsplash.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Wikeo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@wikeo\" \/>\n<meta name=\"twitter:site\" content=\"@wikeo\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Wikeo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.wikeo.be\\\/blog\\\/2016\\\/07\\\/06\\\/menu-edition-adaptatif-tri-annuaire\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.wikeo.be\\\/blog\\\/2016\\\/07\\\/06\\\/menu-edition-adaptatif-tri-annuaire\\\/\"},\"author\":{\"name\":\"Wikeo\",\"@id\":\"https:\\\/\\\/www.wikeo.be\\\/blog\\\/#\\\/schema\\\/person\\\/584f716ac941dc1506a4da467d54996f\"},\"headline\":\"Menu d&rsquo;\u00e9dition adaptatif et tri dans l&rsquo;annuaire\",\"datePublished\":\"2016-07-06T09:45:20+00:00\",\"dateModified\":\"2020-07-12T07:20:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.wikeo.be\\\/blog\\\/2016\\\/07\\\/06\\\/menu-edition-adaptatif-tri-annuaire\\\/\"},\"wordCount\":543,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.wikeo.be\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.wikeo.be\\\/blog\\\/2016\\\/07\\\/06\\\/menu-edition-adaptatif-tri-annuaire\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.wikeo.be\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/gary-chan-YzSZN3qvHeo-unsplash.jpg\",\"keywords\":[\"cr\u00e9er un site\",\"wikeo\"],\"articleSection\":[\"Actualit\u00e9 de Wikeo\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.wikeo.be\\\/blog\\\/2016\\\/07\\\/06\\\/menu-edition-adaptatif-tri-annuaire\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.wikeo.be\\\/blog\\\/2016\\\/07\\\/06\\\/menu-edition-adaptatif-tri-annuaire\\\/\",\"url\":\"https:\\\/\\\/www.wikeo.be\\\/blog\\\/2016\\\/07\\\/06\\\/menu-edition-adaptatif-tri-annuaire\\\/\",\"name\":\"Tri dans l'annuaire, nouveaux captcha et menus sur Wikeo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.wikeo.be\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.wikeo.be\\\/blog\\\/2016\\\/07\\\/06\\\/menu-edition-adaptatif-tri-annuaire\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.wikeo.be\\\/blog\\\/2016\\\/07\\\/06\\\/menu-edition-adaptatif-tri-annuaire\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.wikeo.be\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/gary-chan-YzSZN3qvHeo-unsplash.jpg\",\"datePublished\":\"2016-07-06T09:45:20+00:00\",\"dateModified\":\"2020-07-12T07:20:59+00:00\",\"description\":\"Wikeo v4 avance et cr\u00e9er un site sur Wikeo est encore plus simple avec la v4. Venez d\u00e9couvrir les nouveaut\u00e9s du mois de juillet 2016 !\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.wikeo.be\\\/blog\\\/2016\\\/07\\\/06\\\/menu-edition-adaptatif-tri-annuaire\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.wikeo.be\\\/blog\\\/2016\\\/07\\\/06\\\/menu-edition-adaptatif-tri-annuaire\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.wikeo.be\\\/blog\\\/2016\\\/07\\\/06\\\/menu-edition-adaptatif-tri-annuaire\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.wikeo.be\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/gary-chan-YzSZN3qvHeo-unsplash.jpg\",\"contentUrl\":\"https:\\\/\\\/www.wikeo.be\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/gary-chan-YzSZN3qvHeo-unsplash.jpg\",\"width\":1920,\"height\":1440,\"caption\":\"Pictogramme d'une poubelle\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.wikeo.be\\\/blog\\\/2016\\\/07\\\/06\\\/menu-edition-adaptatif-tri-annuaire\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.wikeo.be\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Menu d&rsquo;\u00e9dition adaptatif et tri dans l&rsquo;annuaire\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.wikeo.be\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.wikeo.be\\\/blog\\\/\",\"name\":\"Cr\u00e9er un site internet avec Wikeo : Astuces et conseils\",\"description\":\"Bien d\u00e9marrer avec Wikeo, astuces r\u00e9f\u00e9rencement et tutoriels\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.wikeo.be\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.wikeo.be\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.wikeo.be\\\/blog\\\/#organization\",\"name\":\"Wikeo\",\"url\":\"https:\\\/\\\/www.wikeo.be\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.wikeo.be\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.wikeo.be\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/android-chrome-512x512-1.png\",\"contentUrl\":\"https:\\\/\\\/www.wikeo.be\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/android-chrome-512x512-1.png\",\"width\":512,\"height\":512,\"caption\":\"Wikeo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.wikeo.be\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wikeocom\",\"https:\\\/\\\/x.com\\\/wikeo\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/wikeo\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.wikeo.be\\\/blog\\\/#\\\/schema\\\/person\\\/584f716ac941dc1506a4da467d54996f\",\"name\":\"Wikeo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5e0a0d2d254145d4a989bbc54394255b58895293f7bfbd03e8b2719884600ffe?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5e0a0d2d254145d4a989bbc54394255b58895293f7bfbd03e8b2719884600ffe?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5e0a0d2d254145d4a989bbc54394255b58895293f7bfbd03e8b2719884600ffe?s=96&d=mm&r=g\",\"caption\":\"Wikeo\"},\"sameAs\":[\"https:\\\/\\\/www.wikeo.be\"],\"url\":\"https:\\\/\\\/www.wikeo.be\\\/blog\\\/author\\\/bistory\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tri dans l'annuaire, nouveaux captcha et menus sur Wikeo","description":"Wikeo v4 avance et cr\u00e9er un site sur Wikeo est encore plus simple avec la v4. Venez d\u00e9couvrir les nouveaut\u00e9s du mois de juillet 2016 !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.wikeo.be\/blog\/2016\/07\/06\/menu-edition-adaptatif-tri-annuaire\/","og_locale":"fr_FR","og_type":"article","og_title":"Tri dans l'annuaire, nouveaux captcha et menus sur Wikeo","og_description":"Wikeo v4 avance et cr\u00e9er un site sur Wikeo est encore plus simple avec la v4. Venez d\u00e9couvrir les nouveaut\u00e9s du mois de juillet 2016 !","og_url":"https:\/\/www.wikeo.be\/blog\/2016\/07\/06\/menu-edition-adaptatif-tri-annuaire\/","og_site_name":"Cr\u00e9er un site internet avec Wikeo : Astuces et conseils","article_publisher":"https:\/\/www.facebook.com\/wikeocom","article_published_time":"2016-07-06T09:45:20+00:00","article_modified_time":"2020-07-12T07:20:59+00:00","og_image":[{"width":1920,"height":1440,"url":"https:\/\/www.wikeo.be\/blog\/wp-content\/uploads\/2016\/07\/gary-chan-YzSZN3qvHeo-unsplash.jpg","type":"image\/jpeg"}],"author":"Wikeo","twitter_card":"summary_large_image","twitter_creator":"@wikeo","twitter_site":"@wikeo","twitter_misc":{"\u00c9crit par":"Wikeo","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.wikeo.be\/blog\/2016\/07\/06\/menu-edition-adaptatif-tri-annuaire\/#article","isPartOf":{"@id":"https:\/\/www.wikeo.be\/blog\/2016\/07\/06\/menu-edition-adaptatif-tri-annuaire\/"},"author":{"name":"Wikeo","@id":"https:\/\/www.wikeo.be\/blog\/#\/schema\/person\/584f716ac941dc1506a4da467d54996f"},"headline":"Menu d&rsquo;\u00e9dition adaptatif et tri dans l&rsquo;annuaire","datePublished":"2016-07-06T09:45:20+00:00","dateModified":"2020-07-12T07:20:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.wikeo.be\/blog\/2016\/07\/06\/menu-edition-adaptatif-tri-annuaire\/"},"wordCount":543,"commentCount":0,"publisher":{"@id":"https:\/\/www.wikeo.be\/blog\/#organization"},"image":{"@id":"https:\/\/www.wikeo.be\/blog\/2016\/07\/06\/menu-edition-adaptatif-tri-annuaire\/#primaryimage"},"thumbnailUrl":"https:\/\/www.wikeo.be\/blog\/wp-content\/uploads\/2016\/07\/gary-chan-YzSZN3qvHeo-unsplash.jpg","keywords":["cr\u00e9er un site","wikeo"],"articleSection":["Actualit\u00e9 de Wikeo"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.wikeo.be\/blog\/2016\/07\/06\/menu-edition-adaptatif-tri-annuaire\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.wikeo.be\/blog\/2016\/07\/06\/menu-edition-adaptatif-tri-annuaire\/","url":"https:\/\/www.wikeo.be\/blog\/2016\/07\/06\/menu-edition-adaptatif-tri-annuaire\/","name":"Tri dans l'annuaire, nouveaux captcha et menus sur Wikeo","isPartOf":{"@id":"https:\/\/www.wikeo.be\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.wikeo.be\/blog\/2016\/07\/06\/menu-edition-adaptatif-tri-annuaire\/#primaryimage"},"image":{"@id":"https:\/\/www.wikeo.be\/blog\/2016\/07\/06\/menu-edition-adaptatif-tri-annuaire\/#primaryimage"},"thumbnailUrl":"https:\/\/www.wikeo.be\/blog\/wp-content\/uploads\/2016\/07\/gary-chan-YzSZN3qvHeo-unsplash.jpg","datePublished":"2016-07-06T09:45:20+00:00","dateModified":"2020-07-12T07:20:59+00:00","description":"Wikeo v4 avance et cr\u00e9er un site sur Wikeo est encore plus simple avec la v4. Venez d\u00e9couvrir les nouveaut\u00e9s du mois de juillet 2016 !","breadcrumb":{"@id":"https:\/\/www.wikeo.be\/blog\/2016\/07\/06\/menu-edition-adaptatif-tri-annuaire\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.wikeo.be\/blog\/2016\/07\/06\/menu-edition-adaptatif-tri-annuaire\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.wikeo.be\/blog\/2016\/07\/06\/menu-edition-adaptatif-tri-annuaire\/#primaryimage","url":"https:\/\/www.wikeo.be\/blog\/wp-content\/uploads\/2016\/07\/gary-chan-YzSZN3qvHeo-unsplash.jpg","contentUrl":"https:\/\/www.wikeo.be\/blog\/wp-content\/uploads\/2016\/07\/gary-chan-YzSZN3qvHeo-unsplash.jpg","width":1920,"height":1440,"caption":"Pictogramme d'une poubelle"},{"@type":"BreadcrumbList","@id":"https:\/\/www.wikeo.be\/blog\/2016\/07\/06\/menu-edition-adaptatif-tri-annuaire\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.wikeo.be\/blog\/"},{"@type":"ListItem","position":2,"name":"Menu d&rsquo;\u00e9dition adaptatif et tri dans l&rsquo;annuaire"}]},{"@type":"WebSite","@id":"https:\/\/www.wikeo.be\/blog\/#website","url":"https:\/\/www.wikeo.be\/blog\/","name":"Cr\u00e9er un site internet avec Wikeo : Astuces et conseils","description":"Bien d\u00e9marrer avec Wikeo, astuces r\u00e9f\u00e9rencement et tutoriels","publisher":{"@id":"https:\/\/www.wikeo.be\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.wikeo.be\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.wikeo.be\/blog\/#organization","name":"Wikeo","url":"https:\/\/www.wikeo.be\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.wikeo.be\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.wikeo.be\/blog\/wp-content\/uploads\/2020\/06\/android-chrome-512x512-1.png","contentUrl":"https:\/\/www.wikeo.be\/blog\/wp-content\/uploads\/2020\/06\/android-chrome-512x512-1.png","width":512,"height":512,"caption":"Wikeo"},"image":{"@id":"https:\/\/www.wikeo.be\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wikeocom","https:\/\/x.com\/wikeo","https:\/\/www.linkedin.com\/company\/wikeo\/"]},{"@type":"Person","@id":"https:\/\/www.wikeo.be\/blog\/#\/schema\/person\/584f716ac941dc1506a4da467d54996f","name":"Wikeo","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/5e0a0d2d254145d4a989bbc54394255b58895293f7bfbd03e8b2719884600ffe?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5e0a0d2d254145d4a989bbc54394255b58895293f7bfbd03e8b2719884600ffe?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5e0a0d2d254145d4a989bbc54394255b58895293f7bfbd03e8b2719884600ffe?s=96&d=mm&r=g","caption":"Wikeo"},"sameAs":["https:\/\/www.wikeo.be"],"url":"https:\/\/www.wikeo.be\/blog\/author\/bistory\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.wikeo.be\/blog\/wp-json\/wp\/v2\/posts\/1024","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wikeo.be\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.wikeo.be\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.wikeo.be\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.wikeo.be\/blog\/wp-json\/wp\/v2\/comments?post=1024"}],"version-history":[{"count":9,"href":"https:\/\/www.wikeo.be\/blog\/wp-json\/wp\/v2\/posts\/1024\/revisions"}],"predecessor-version":[{"id":1173,"href":"https:\/\/www.wikeo.be\/blog\/wp-json\/wp\/v2\/posts\/1024\/revisions\/1173"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.wikeo.be\/blog\/wp-json\/wp\/v2\/media\/1172"}],"wp:attachment":[{"href":"https:\/\/www.wikeo.be\/blog\/wp-json\/wp\/v2\/media?parent=1024"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.wikeo.be\/blog\/wp-json\/wp\/v2\/categories?post=1024"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.wikeo.be\/blog\/wp-json\/wp\/v2\/tags?post=1024"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}